{"id":916,"name":"ernesto","url":"http:\/\/www.dafumachinery.com","description":"","link":"http:\/\/www.dibenzoylmethane.com\/blog\/author\/ernesto\/","slug":"ernesto","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/5b660d0c6047fd476aedc5a24931f49088c9c9440a25c55e089c0bb9274e9dfd?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/5b660d0c6047fd476aedc5a24931f49088c9c9440a25c55e089c0bb9274e9dfd?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/5b660d0c6047fd476aedc5a24931f49088c9c9440a25c55e089c0bb9274e9dfd?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"http:\/\/www.dibenzoylmethane.com\/blog\/wp-json\/wp\/v2\/users\/916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.dibenzoylmethane.com\/blog\/wp-json\/wp\/v2\/users"}]}}