{"id":3167,"count":0,"description":"","link":"http:\/\/www.dibenzoylmethane.com\/blog\/tag\/aluminum-plate-4e78-3277b3\/","name":"Aluminum Plate","slug":"aluminum-plate-4e78-3277b3","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.dibenzoylmethane.com\/blog\/wp-json\/wp\/v2\/tags\/3167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.dibenzoylmethane.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.dibenzoylmethane.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.dibenzoylmethane.com\/blog\/wp-json\/wp\/v2\/posts?tags=3167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}