{"id":3105,"count":0,"description":"","link":"http:\/\/www.dibenzoylmethane.com\/blog\/tag\/lawn-light-447b-fb6873\/","name":"Lawn Light","slug":"lawn-light-447b-fb6873","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.dibenzoylmethane.com\/blog\/wp-json\/wp\/v2\/tags\/3105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.dibenzoylmethane.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.dibenzoylmethane.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.dibenzoylmethane.com\/blog\/wp-json\/wp\/v2\/posts?tags=3105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}